{"id":171,"date":"2021-09-22T07:15:00","date_gmt":"2021-09-22T05:15:00","guid":{"rendered":"https:\/\/www.covalgo.at\/blog\/?p=171"},"modified":"2021-09-17T16:05:24","modified_gmt":"2021-09-17T14:05:24","slug":"tutorial-requirements-engineering-beispiel-einer-nichtfunktionalen-anforderung","status":"publish","type":"post","link":"https:\/\/www.covalgo.at\/blog\/2021\/09\/22\/tutorial-requirements-engineering-beispiel-einer-nichtfunktionalen-anforderung\/","title":{"rendered":"Tutorial: Requirements Engineering &#8211; Beispiel einer nichtfunktionalen Anforderung"},"content":{"rendered":"\n<p>Nicht-funktionale Anforderungen m\u00fcssen im Analyse- und Entwicklungszyklus fr\u00fchzeitig ber\u00fccksichtigt werden. Dieses Tutorial zeigt an einem konkreten Beispiel zur Performance, welche \u00dcberlegungen erforderlich sind und wie man damit umgeht.<\/p>\n\n\n\n<p> Besuchen Sie unser <a href=\"https:\/\/youtu.be\/pBadn9ouoCE\" target=\"_blank\" rel=\"noreferrer noopener\">Tutorial <\/a>auf unserem Youtube Channel <a rel=\"noreferrer noopener\" href=\"https:\/\/www.youtube.com\/channel\/UCRMAc8yzzCQR6lbvBCsZQnQ\" target=\"_blank\">Business Analyse &amp; Co<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicht-funktionale Anforderungen m\u00fcssen im Analyse- und Entwicklungszyklus fr\u00fchzeitig ber\u00fccksichtigt werden. Dieses Tutorial zeigt an einem konkreten Beispiel zur Performance, welche \u00dcberlegungen erforderlich sind und wie man damit umgeht. Besuchen Sie unser Tutorial auf unserem Youtube Channel Business Analyse &amp; Co.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-171","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/posts\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":1,"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/posts\/171\/revisions"}],"predecessor-version":[{"id":172,"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/posts\/171\/revisions\/172"}],"wp:attachment":[{"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/media?parent=171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/categories?post=171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.covalgo.at\/blog\/wp-json\/wp\/v2\/tags?post=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}